{"id":336,"count":0,"description":"","link":"https:\/\/corporate.idkids.com\/en\/tag\/sedd2019-en\/","name":"SEDD2019","slug":"sedd2019-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SEDD2019 Archives - \u00cfDKIDS.COMMUNITY<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/corporate.idkids.com\/en\/tag\/sedd2019-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SEDD2019 Archives - \u00cfDKIDS.COMMUNITY\" \/>\n<meta property=\"og:url\" content=\"https:\/\/corporate.idkids.com\/en\/tag\/sedd2019-en\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00cfDKIDS.COMMUNITY\" \/>\n<meta property=\"og:image\" content=\"https:\/\/corporate.idkids.com\/wp-content\/uploads\/2020\/07\/idkids-corporate-og-default-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/corporate.idkids.com\\\/en\\\/tag\\\/sedd2019-en\\\/\",\"url\":\"https:\\\/\\\/corporate.idkids.com\\\/en\\\/tag\\\/sedd2019-en\\\/\",\"name\":\"SEDD2019 Archives - \u00cfDKIDS.COMMUNITY\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/corporate.idkids.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/corporate.idkids.com\\\/en\\\/tag\\\/sedd2019-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/corporate.idkids.com\\\/en\\\/tag\\\/sedd2019-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/corporate.idkids.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SEDD2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/corporate.idkids.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/corporate.idkids.com\\\/en\\\/\",\"name\":\"\u00cfDKIDS.COMMUNITY\",\"description\":\"Let's work to make a better world for growing children\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/corporate.idkids.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SEDD2019 Archives - \u00cfDKIDS.COMMUNITY","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/corporate.idkids.com\/en\/tag\/sedd2019-en\/","og_locale":"en_US","og_type":"article","og_title":"SEDD2019 Archives - \u00cfDKIDS.COMMUNITY","og_url":"https:\/\/corporate.idkids.com\/en\/tag\/sedd2019-en\/","og_site_name":"\u00cfDKIDS.COMMUNITY","og_image":[{"width":1200,"height":800,"url":"https:\/\/corporate.idkids.com\/wp-content\/uploads\/2020\/07\/idkids-corporate-og-default-image.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/corporate.idkids.com\/en\/tag\/sedd2019-en\/","url":"https:\/\/corporate.idkids.com\/en\/tag\/sedd2019-en\/","name":"SEDD2019 Archives - \u00cfDKIDS.COMMUNITY","isPartOf":{"@id":"https:\/\/corporate.idkids.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/corporate.idkids.com\/en\/tag\/sedd2019-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/corporate.idkids.com\/en\/tag\/sedd2019-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/corporate.idkids.com\/en\/"},{"@type":"ListItem","position":2,"name":"SEDD2019"}]},{"@type":"WebSite","@id":"https:\/\/corporate.idkids.com\/en\/#website","url":"https:\/\/corporate.idkids.com\/en\/","name":"\u00cfDKIDS.COMMUNITY","description":"Let's work to make a better world for growing children","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/corporate.idkids.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/corporate.idkids.com\/en\/wp-json\/wp\/v2\/tags\/336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corporate.idkids.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/corporate.idkids.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/corporate.idkids.com\/en\/wp-json\/wp\/v2\/posts?tags=336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}